{"id":2380,"date":"2021-12-25T21:18:30","date_gmt":"2021-12-25T20:18:30","guid":{"rendered":"http:\/\/piaer.net\/?p=2380"},"modified":"2021-12-25T21:18:32","modified_gmt":"2021-12-25T20:18:32","slug":"gastvortrag-von-dora-celentano-kuenstliche-intelligenz-und-reproduktion-von-geschlechternormen-durch-algorithmen-der-repraesentation","status":"publish","type":"post","link":"http:\/\/piaer.net\/en\/gastvortrag-von-dora-celentano-kuenstliche-intelligenz-und-reproduktion-von-geschlechternormen-durch-algorithmen-der-repraesentation\/","title":{"rendered":"Gastvortrag von Dora Celentano: K\u00fcnstliche Intelligenz und Reproduktion von Geschlechternormen durch Algorithmen der Repr\u00e4sentation"},"content":{"rendered":"<p>Der t\u00e4gliche Umgang mit Formen der Selbstdarstellung in Social Media geh\u00f6ren f\u00fcr Jugendliche zum medialen Konsumstandard, teilweise auch zur eigenen medialen Praxis der Repr\u00e4sentation.<br>Gerade Frauen sind mehrheitlich der Beurteilung aufgrund ihrer \u00e4u\u00dferlichen Erscheinung ausgesetzt und haben gesellschaftlich oft einen gewissen Sch\u00f6nheitsdruck. Das Zuschreiben geschlechtstypischer Merkmale und Verhaltensweisen ist tief in unserer Gesellschaft verankert und wird oft unterbewusst von Generation zu Generation weitergegeben.<br>Die Verbindung vom Umgang mit k\u00fcnstlicher Intelligenz, einer feministischen Sichtweise, Funktionen der Selbstdarstellung in Social Media und einer k\u00fcnstlerischen Auseinandersetzung, bilden im Zusammenschluss die Idee f\u00fcr das Unterrichtsprojekt, das im Rahmen des Saloons vorgestellt wird.<\/p>\n\n\n\n<p><strong>Dora Celentano<\/strong>&nbsp;ist K\u00fcnstlerin, Kunstvermittlerin und Kunstp\u00e4dagogin. Sie studierte an der Kunstakademie D\u00fcsseldorf bei Prof. Rita Mc.Bride und war Meistersch\u00fclerin von Prof. Stefan K\u00fcrten.<br>Arbeitskontexte: Museumsguide am Museum Folkwang Essen, Koordinatorin des Austauschprogramms in D\u00fcsseldorf der Malerei-Master-Studierenden der Alfred University New York, SoSe 2021 Lehrauftrag Grundlagen der Gestaltung an der Folkwang Universit\u00e4t der K\u00fcnste. Sie arbeitet und lebt in D\u00fcsseldorf.<\/p>\n\n\n\n<p>Alle Saloon-Veranstaltungen finden im Wintersemester 2021 online \u00fcber Zoom statt. Die jeweiligen Zugangsdaten erhalten die studentischen Teilnehmer*innen \u00fcber ihren ILIAS-Kurs. Externe Interessierte wenden sich bitte rechtzeitig per Email an die Veranstalter*innen:<br>Jane Eschment:<a href=\"mailto:jane.eschment@uni-koeln.de\">&nbsp;jane.eschment@uni-koeln.de<\/a><br>Gesa Krebber:&nbsp;<a href=\"mailto:g.krebber@uni-koeln.de\">g.krebber@uni-koeln.de<\/a><\/p>\n\n\n\n<p><em>Bildcredits: Dora Celentano<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">DETAILS<\/h5>\n\n\n\n<p>12. Januar 2022<br>18-19:30 Uhr<br>online<\/p>","protected":false},"excerpt":{"rendered":"<p>Der t\u00e4gliche Umgang mit Formen der Selbstdarstellung in Social Media geh\u00f6ren f\u00fcr Jugendliche zum medialen Konsumstandard, teilweise auch zur eigenen medialen Praxis der Repr\u00e4sentation.Gerade Frauen sind mehrheitlich der Beurteilung aufgrund ihrer \u00e4u\u00dferlichen Erscheinung ausgesetzt und haben gesellschaftlich oft einen gewissen Sch\u00f6nheitsdruck. Das Zuschreiben geschlechtstypischer Merkmale und Verhaltensweisen ist tief in unserer Gesellschaft verankert und wird [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":2383,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[392,77,472,43,487],"class_list":["post-2380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-aesthetische-erfahrung","tag-feminismus","tag-immermittwochs","tag-internet","tag-kuenstlerische-praxis"],"acf":[],"jetpack_featured_media_url":"https:\/\/piaer.net\/wp-content\/uploads\/2021\/12\/Ergebnisse-1-1024x683-1.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/piaer.net\/en\/wp-json\/wp\/v2\/posts\/2380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/piaer.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/piaer.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/piaer.net\/en\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"http:\/\/piaer.net\/en\/wp-json\/wp\/v2\/comments?post=2380"}],"version-history":[{"count":2,"href":"http:\/\/piaer.net\/en\/wp-json\/wp\/v2\/posts\/2380\/revisions"}],"predecessor-version":[{"id":2382,"href":"http:\/\/piaer.net\/en\/wp-json\/wp\/v2\/posts\/2380\/revisions\/2382"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/piaer.net\/en\/wp-json\/wp\/v2\/media\/2383"}],"wp:attachment":[{"href":"http:\/\/piaer.net\/en\/wp-json\/wp\/v2\/media?parent=2380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/piaer.net\/en\/wp-json\/wp\/v2\/categories?post=2380"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/piaer.net\/en\/wp-json\/wp\/v2\/tags?post=2380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}